{"id":275,"count":553,"description":"","link":"https:\/\/idolhorse.com\/zh-hant\/horse-racing-news\/world\/","name":"\u74b0\u7403\u8cfd\u4e8b\u65b0\u805e","slug":"world","taxonomy":"category","parent":273,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u74b0\u7403\u8cfd\u4e8b\u65b0\u805e Archives - Idol Horse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idolhorse.com\/zh-hant\/horse-racing-news\/world\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u74b0\u7403\u8cfd\u4e8b\u65b0\u805e Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idolhorse.com\/zh-hant\/horse-racing-news\/world\/\" \/>\n<meta property=\"og:site_name\" content=\"Idol Horse\" \/>\n<meta property=\"og:image\" content=\"https:\/\/idolhorse.com\/wp-content\/uploads\/2024\/06\/IdolHorseDotCom.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/horse-racing-news\\\/world\\\/\",\"url\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/horse-racing-news\\\/world\\\/\",\"name\":\"\u74b0\u7403\u8cfd\u4e8b\u65b0\u805e Archives - Idol Horse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/horse-racing-news\\\/world\\\/#breadcrumb\"},\"inLanguage\":\"zh-hant\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/horse-racing-news\\\/world\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u8cfd\u99ac\u65b0\u805e\",\"item\":\"https:\\\/\\\/idolhorse.com\\\/horse-racing-news\\\/?lang=zh-hant\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u74b0\u7403\u8cfd\u4e8b\u65b0\u805e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/#website\",\"url\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/\",\"name\":\"Idol Horse\",\"description\":\"Global Racing News Network\",\"publisher\":{\"@id\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-hant\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/#organization\",\"name\":\"Idol Horse\",\"alternateName\":\"Idolhorse\",\"url\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-hant\",\"@id\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/idolhorse.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/idol-horse-logo.png\",\"contentUrl\":\"https:\\\/\\\/idolhorse.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/idol-horse-logo.png\",\"width\":389,\"height\":389,\"caption\":\"Idol Horse\"},\"image\":{\"@id\":\"https:\\\/\\\/idolhorse.com\\\/zh-hant\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u74b0\u7403\u8cfd\u4e8b\u65b0\u805e Archives - Idol Horse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idolhorse.com\/zh-hant\/horse-racing-news\/world\/","og_locale":"en_US","og_type":"article","og_title":"\u74b0\u7403\u8cfd\u4e8b\u65b0\u805e Archives","og_url":"https:\/\/idolhorse.com\/zh-hant\/horse-racing-news\/world\/","og_site_name":"Idol Horse","og_image":[{"width":1200,"height":675,"url":"https:\/\/idolhorse.com\/wp-content\/uploads\/2024\/06\/IdolHorseDotCom.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/idolhorse.com\/zh-hant\/horse-racing-news\/world\/","url":"https:\/\/idolhorse.com\/zh-hant\/horse-racing-news\/world\/","name":"\u74b0\u7403\u8cfd\u4e8b\u65b0\u805e Archives - Idol Horse","isPartOf":{"@id":"https:\/\/idolhorse.com\/zh-hant\/#website"},"breadcrumb":{"@id":"https:\/\/idolhorse.com\/zh-hant\/horse-racing-news\/world\/#breadcrumb"},"inLanguage":"zh-hant"},{"@type":"BreadcrumbList","@id":"https:\/\/idolhorse.com\/zh-hant\/horse-racing-news\/world\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/idolhorse.com\/zh-hant\/"},{"@type":"ListItem","position":2,"name":"\u8cfd\u99ac\u65b0\u805e","item":"https:\/\/idolhorse.com\/horse-racing-news\/?lang=zh-hant"},{"@type":"ListItem","position":3,"name":"\u74b0\u7403\u8cfd\u4e8b\u65b0\u805e"}]},{"@type":"WebSite","@id":"https:\/\/idolhorse.com\/zh-hant\/#website","url":"https:\/\/idolhorse.com\/zh-hant\/","name":"Idol Horse","description":"Global Racing News Network","publisher":{"@id":"https:\/\/idolhorse.com\/zh-hant\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idolhorse.com\/zh-hant\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-hant"},{"@type":"Organization","@id":"https:\/\/idolhorse.com\/zh-hant\/#organization","name":"Idol Horse","alternateName":"Idolhorse","url":"https:\/\/idolhorse.com\/zh-hant\/","logo":{"@type":"ImageObject","inLanguage":"zh-hant","@id":"https:\/\/idolhorse.com\/zh-hant\/#\/schema\/logo\/image\/","url":"https:\/\/idolhorse.com\/wp-content\/uploads\/2024\/07\/idol-horse-logo.png","contentUrl":"https:\/\/idolhorse.com\/wp-content\/uploads\/2024\/07\/idol-horse-logo.png","width":389,"height":389,"caption":"Idol Horse"},"image":{"@id":"https:\/\/idolhorse.com\/zh-hant\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/idolhorse.com\/zh-hant\/wp-json\/wp\/v2\/categories\/275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/idolhorse.com\/zh-hant\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/idolhorse.com\/zh-hant\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/idolhorse.com\/zh-hant\/wp-json\/wp\/v2\/categories\/273"}],"wp:post_type":[{"href":"https:\/\/idolhorse.com\/zh-hant\/wp-json\/wp\/v2\/posts?categories=275"},{"href":"https:\/\/idolhorse.com\/zh-hant\/wp-json\/wp\/v2\/article_post?categories=275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}